{"id":158788,"date":"2023-09-12T06:54:57","date_gmt":"2023-09-12T04:54:57","guid":{"rendered":"https:\/\/oradea.ro\/for-citizens\/parking\/"},"modified":"2024-01-16T09:43:29","modified_gmt":"2024-01-16T09:43:29","slug":"parking","status":"publish","type":"page","link":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/","title":{"rendered":"Parking"},"content":{"rendered":"<div class=\"min-w-[100vw] h-[350px] md:h-[500px] ml-[calc(50%-50vw)] flex items-end bg-no-repeat bg-white bg-cover bg-center px-5\" style=\"background-image: url(https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg);\">\r\n                    <div class=\"w-full max-w-7xl mx-auto mb-6\">\r\n                        <h1 class=\"my-0 text-white font-extrabold font-open-sans text-3xl md:text-6xl [text-shadow:_0_1px_4px_rgb(0_0_0_\/_50%)]\">Parking<\/h1>\r\n                    <\/div>\r\n                <\/div><div class=\"!px-5\"><div class=\"breadcrumbs w-full max-w-7xl mx-auto grid md:flex flex-wrap items-center py-4 test\"><div><a href=\"https:\/\/oradea.ro\/en\/\"><span class=\"fas fa-home text-[#ABAEB3]\"><\/span><\/a><span class=\"md:hidden\"><span class=\"fas fa-chevron-down mx-5 text-xs text-[#ABAEB3] hover:text-black\/50 transition-all\"><\/span><\/span><span class=\"hidden md:inline\"><span class=\"fas fa-chevron-right mx-5 text-xs text-[#ABAEB3] hover:text-black\/50 transition-all\"><\/span><\/span><\/div><span class=\"font-poppins font-semibold uppercase text-black\/60\">Parking<\/span><\/div><\/div>\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"158788\" class=\"elementor elementor-158788 elementor-8006\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b82f4 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-parent\" data-id=\"c4b82f4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6155a07 e-flex e-con-boxed wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"6155a07\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f00aecf e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"f00aecf\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-380ee84 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"380ee84\" data-element_type=\"container\" href=\"\/en\/for-citizens\/parking\/public-street-parking\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8abf928 elementor-widget elementor-widget-heading\" data-id=\"8abf928\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Public street parking<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-b889b81 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b889b81\" data-element_type=\"container\" href=\"\/en\/for-citizens\/parking\/off-street-parking-multi-storey\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2de1443 elementor-widget elementor-widget-heading\" data-id=\"2de1443\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Off-street parking (multi-storey)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-1867971 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"1867971\" data-element_type=\"container\" href=\"\/en\/for-citizens\/parking\/home-parking-lots\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a74e552 elementor-widget elementor-widget-heading\" data-id=\"a74e552\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Home parking lots<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dba34ac e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"dba34ac\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-5efde84 e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"5efde84\" data-element_type=\"container\" href=\"\/en\/for-citizens\/parking\/car-pick-ups-with-trucks\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5278ee elementor-widget elementor-widget-heading\" data-id=\"f5278ee\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Car pick-ups with trucks<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-f11c38b e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"f11c38b\" data-element_type=\"container\" href=\"\/en\/for-citizens\/parking\/parking-service\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a36e0b4 elementor-widget elementor-widget-heading\" data-id=\"a36e0b4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parking service<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-b07055c e-con-full e-flex wpr-particle-no wpr-jarallax-no wpr-parallax-no wpr-sticky-section-no e-con e-child\" data-id=\"b07055c\" data-element_type=\"container\">\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Parking Parking Public street parking Off-street parking (multi-storey) Home parking lots Car pick-ups with trucks Parking service<\/p>\n","protected":false},"author":1,"featured_media":24395,"parent":136570,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ep_exclude_from_search":false,"footnotes":""},"class_list":["post-158788","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parking - Oradea.ro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parking - Oradea.ro\" \/>\n<meta property=\"og:description\" content=\"Parking Parking Public street parking Off-street parking (multi-storey) Home parking lots Car pick-ups with trucks Parking service\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/\" \/>\n<meta property=\"og:site_name\" content=\"Oradea.ro\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T09:43:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/\",\"url\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/\",\"name\":\"Parking - Oradea.ro\",\"isPartOf\":{\"@id\":\"https:\/\/oradea.ro\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg\",\"datePublished\":\"2023-09-12T04:54:57+00:00\",\"dateModified\":\"2024-01-16T09:43:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage\",\"url\":\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg\",\"contentUrl\":\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\",\"item\":\"https:\/\/oradea.ro\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"For citizens\",\"item\":\"https:\/\/oradea.ro\/en\/for-citizens\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Parking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/oradea.ro\/#website\",\"url\":\"https:\/\/oradea.ro\/\",\"name\":\"Oradea.ro\",\"description\":\"Site-ul oficial al Prim\u0103riei Municipiului Oradea\",\"publisher\":{\"@id\":\"https:\/\/oradea.ro\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/oradea.ro\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/oradea.ro\/#organization\",\"name\":\"Oradea.ro\",\"url\":\"https:\/\/oradea.ro\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/oradea.ro\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/06\/footer_logo.svg\",\"contentUrl\":\"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/06\/footer_logo.svg\",\"width\":218,\"height\":53,\"caption\":\"Oradea.ro\"},\"image\":{\"@id\":\"https:\/\/oradea.ro\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parking - Oradea.ro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/","og_locale":"en_US","og_type":"article","og_title":"Parking - Oradea.ro","og_description":"Parking Parking Public street parking Off-street parking (multi-storey) Home parking lots Car pick-ups with trucks Parking service","og_url":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/","og_site_name":"Oradea.ro","article_modified_time":"2024-01-16T09:43:29+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/","url":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/","name":"Parking - Oradea.ro","isPartOf":{"@id":"https:\/\/oradea.ro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage"},"image":{"@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage"},"thumbnailUrl":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg","datePublished":"2023-09-12T04:54:57+00:00","dateModified":"2024-01-16T09:43:29+00:00","breadcrumb":{"@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/oradea.ro\/en\/for-citizens\/parking\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#primaryimage","url":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg","contentUrl":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/10\/parcari.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/oradea.ro\/en\/for-citizens\/parking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"","item":"https:\/\/oradea.ro\/en\/"},{"@type":"ListItem","position":2,"name":"For citizens","item":"https:\/\/oradea.ro\/en\/for-citizens\/"},{"@type":"ListItem","position":3,"name":"Parking"}]},{"@type":"WebSite","@id":"https:\/\/oradea.ro\/#website","url":"https:\/\/oradea.ro\/","name":"Oradea.ro","description":"Site-ul oficial al Prim\u0103riei Municipiului Oradea","publisher":{"@id":"https:\/\/oradea.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oradea.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/oradea.ro\/#organization","name":"Oradea.ro","url":"https:\/\/oradea.ro\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/oradea.ro\/#\/schema\/logo\/image\/","url":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/06\/footer_logo.svg","contentUrl":"https:\/\/oradea.ro\/wp-content\/uploads\/2023\/06\/footer_logo.svg","width":218,"height":53,"caption":"Oradea.ro"},"image":{"@id":"https:\/\/oradea.ro\/#\/schema\/logo\/image\/"}}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:15:13","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/pages\/158788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/comments?post=158788"}],"version-history":[{"count":18,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/pages\/158788\/revisions"}],"predecessor-version":[{"id":190366,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/pages\/158788\/revisions\/190366"}],"up":[{"embeddable":true,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/pages\/136570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/media\/24395"}],"wp:attachment":[{"href":"https:\/\/oradea.ro\/en\/wp-json\/wp\/v2\/media?parent=158788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}